{"id":5876,"date":"2022-07-27T15:21:39","date_gmt":"2022-07-27T15:21:39","guid":{"rendered":"https:\/\/www.ativ.pt\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/"},"modified":"2022-09-15T16:03:22","modified_gmt":"2022-09-15T16:03:22","slug":"entretien-des-espaces-verts-chez-volkswagen-autoeuropa","status":"publish","type":"post","link":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/","title":{"rendered":"Entretien des espaces verts chez Volkswagen AutoEuropa"},"content":{"rendered":"\n<p><\/p>\n\n<p>Marque de confiance et d\u2019excellence sur le march\u00e9 de l\u2019am\u00e9nagement paysager, avec une action sp\u00e9cialis\u00e9e dans la planification, la construction et l\u2019entretien d\u2019espaces verts, Mota-Engil ATIV garantit le contr\u00f4le et la qualit\u00e9 du service requis par le client.<\/p>\n\n<p>Dans l\u2019objectif clair de contribuer au maintien et \u00e0 l\u2019am\u00e9lioration de la qualit\u00e9 des espaces verts d\u2019AutoEuropa et d\u2019augmenter ainsi la qualit\u00e9 de vie de ses employ\u00e9s, ATIV est charg\u00e9e du nettoyage des espaces et de la lutte contre les mauvaises herbes, de la conservation des pelouses, des plantes herbac\u00e9es et des arbres, palmiers et arbustes, en portant une attention particuli\u00e8re au syst\u00e8me d\u2019arrosage.<\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"511\" data-id=\"3845\" src=\"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa1-1-1024x511.jpg\" alt=\"\" class=\"wp-image-3845\" srcset=\"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa1-1-1024x511.jpg 1024w, https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa1-1-300x150.jpg 300w, https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa1-1-768x383.jpg 768w, https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa1-1.jpg 1265w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n\n<p>En plus de l\u2019entretien, du d\u00e9sherbage et du nettoyage g\u00e9n\u00e9ral des zones pav\u00e9es, des chemins, des gravi\u00e8res et autres structures, l\u2019entretien des parterres de fleurs sera assur\u00e9.<\/p>\n\n<p>Soutenue par des solutions interdisciplinaires qui associent la mise en valeur du territoire, le d\u00e9veloppement durable et la qualit\u00e9 de vie des usagers des espaces qu\u2019elle con\u00e7oit, construit et entretient, Mota-Engil ATIV se lance dans un nouveau contrat stimulant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mota-Engil ATIV, par le biais de son secteur d\u2019am\u00e9nagement paysager, va assurer l\u2019entretien des espaces verts de Volkswagen AutoEuropa.<\/p>\n","protected":false},"author":2,"featured_media":4762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[206,207],"class_list":["post-5876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-ativ","tag-mota-engil-ativ"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV\" \/>\n<meta property=\"og:description\" content=\"Mota-Engil ATIV, par le biais de son secteur d\u2019am\u00e9nagement paysager, va assurer l\u2019entretien des espaces verts de Volkswagen AutoEuropa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/\" \/>\n<meta property=\"og:site_name\" content=\"Mota-Engil ATIV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotaEngilATIV\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T15:21:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T16:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1267\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Susana Guerreiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susana Guerreiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/\"},\"author\":{\"name\":\"Susana Guerreiro\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#\\\/schema\\\/person\\\/76cd49f91ef96b6902453415264f0c55\"},\"headline\":\"Entretien des espaces verts chez Volkswagen AutoEuropa\",\"datePublished\":\"2022-07-27T15:21:39+00:00\",\"dateModified\":\"2022-09-15T16:03:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/autoeuropa2.jpg\",\"keywords\":[\"ATIV\",\"Mota-Engil ATIV\"],\"articleSection\":[\"Article\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/\",\"url\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/\",\"name\":\"Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/autoeuropa2.jpg\",\"datePublished\":\"2022-07-27T15:21:39+00:00\",\"dateModified\":\"2022-09-15T16:03:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/autoeuropa2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/autoeuropa2.jpg\",\"width\":1267,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/2022\\\/07\\\/27\\\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entretien des espaces verts chez Volkswagen AutoEuropa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/\",\"name\":\"Mota-Engil ATIV\",\"description\":\"Gest\u00e3o e Manuten\u00e7\u00e3o de Ativos\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#organization\",\"name\":\"Mota-Engil ATIV\",\"url\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-ativ-cor-1.svg\",\"contentUrl\":\"https:\\\/\\\/www.ativ.pt\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-ativ-cor-1.svg\",\"width\":250,\"height\":100,\"caption\":\"Mota-Engil ATIV\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MotaEngilATIV\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mota_engil_ativ\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/motaengil-ativ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ativ.pt\\\/fr\\\/#\\\/schema\\\/person\\\/76cd49f91ef96b6902453415264f0c55\",\"name\":\"Susana Guerreiro\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/","og_locale":"fr_FR","og_type":"article","og_title":"Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV","og_description":"Mota-Engil ATIV, par le biais de son secteur d\u2019am\u00e9nagement paysager, va assurer l\u2019entretien des espaces verts de Volkswagen AutoEuropa.","og_url":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/","og_site_name":"Mota-Engil ATIV","article_publisher":"https:\/\/www.facebook.com\/MotaEngilATIV\/","article_published_time":"2022-07-27T15:21:39+00:00","article_modified_time":"2022-09-15T16:03:22+00:00","og_image":[{"width":1267,"height":631,"url":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg","type":"image\/jpeg"}],"author":"Susana Guerreiro","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Susana Guerreiro","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#article","isPartOf":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/"},"author":{"name":"Susana Guerreiro","@id":"https:\/\/www.ativ.pt\/fr\/#\/schema\/person\/76cd49f91ef96b6902453415264f0c55"},"headline":"Entretien des espaces verts chez Volkswagen AutoEuropa","datePublished":"2022-07-27T15:21:39+00:00","dateModified":"2022-09-15T16:03:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/www.ativ.pt\/fr\/#organization"},"image":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg","keywords":["ATIV","Mota-Engil ATIV"],"articleSection":["Article"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/","url":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/","name":"Entretien des espaces verts chez Volkswagen AutoEuropa - Mota-Engil ATIV","isPartOf":{"@id":"https:\/\/www.ativ.pt\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#primaryimage"},"image":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg","datePublished":"2022-07-27T15:21:39+00:00","dateModified":"2022-09-15T16:03:22+00:00","breadcrumb":{"@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#primaryimage","url":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg","contentUrl":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/07\/autoeuropa2.jpg","width":1267,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/www.ativ.pt\/fr\/2022\/07\/27\/entretien-des-espaces-verts-chez-volkswagen-autoeuropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.ativ.pt\/fr\/"},{"@type":"ListItem","position":2,"name":"Entretien des espaces verts chez Volkswagen AutoEuropa"}]},{"@type":"WebSite","@id":"https:\/\/www.ativ.pt\/fr\/#website","url":"https:\/\/www.ativ.pt\/fr\/","name":"Mota-Engil ATIV","description":"Gest\u00e3o e Manuten\u00e7\u00e3o de Ativos","publisher":{"@id":"https:\/\/www.ativ.pt\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ativ.pt\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ativ.pt\/fr\/#organization","name":"Mota-Engil ATIV","url":"https:\/\/www.ativ.pt\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ativ.pt\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/04\/logo-ativ-cor-1.svg","contentUrl":"https:\/\/www.ativ.pt\/wp-content\/uploads\/2022\/04\/logo-ativ-cor-1.svg","width":250,"height":100,"caption":"Mota-Engil ATIV"},"image":{"@id":"https:\/\/www.ativ.pt\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MotaEngilATIV\/","https:\/\/www.instagram.com\/mota_engil_ativ\/","https:\/\/www.linkedin.com\/company\/motaengil-ativ"]},{"@type":"Person","@id":"https:\/\/www.ativ.pt\/fr\/#\/schema\/person\/76cd49f91ef96b6902453415264f0c55","name":"Susana Guerreiro"}]}},"_links":{"self":[{"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/posts\/5876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/comments?post=5876"}],"version-history":[{"count":1,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/posts\/5876\/revisions"}],"predecessor-version":[{"id":5877,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/posts\/5876\/revisions\/5877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/media\/4762"}],"wp:attachment":[{"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/media?parent=5876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/categories?post=5876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ativ.pt\/fr\/wp-json\/wp\/v2\/tags?post=5876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}